{"id":1676,"date":"2020-06-04T12:59:27","date_gmt":"2020-06-04T12:59:27","guid":{"rendered":"https:\/\/flexoffice.swiss\/das-neue-normal-flexoffice-ist-geruestet-fuer-die-zukunft\/"},"modified":"2025-07-31T11:20:04","modified_gmt":"2025-07-31T11:20:04","slug":"das-neue-normal-flexoffice-ist-geruestet-fuer-die-zukunft","status":"publish","type":"post","link":"https:\/\/flexoffice.swiss\/en\/das-neue-normal-flexoffice-ist-geruestet-fuer-die-zukunft\/","title":{"rendered":"Das neue Normal \u2013 FlexOffice ist ger\u00fcstet f\u00fcr die Zukunft"},"content":{"rendered":"\n<p>Wir sind uns jedoch bewusst, dass sich die Bed\u00fcrfnisse der Menschen \u00fcber die vergangenen Wochen ver\u00e4ndert haben, dass wir nun in einer neuen Realit\u00e4t leben \u2013 ein \u00abneues Normal\u00bb, welches voraussichtlich bloss einen ersten Schritt in einem gr\u00f6sseren, globalen Transformationsprozess darstellt.<\/p>\n\n\n\n<p>FlexOffice hat es sich deshalb zum Ziel gesetzt, dieses Konzept des \u00abneuen Normals\u00bb in seine Gesch\u00e4ftsphilosophie zu integrieren. Was das heisst? Wir werden uns stetig weiterentwickeln, um auf neue Ver\u00e4nderungen antworten und die Zukunft der Arbeit aktiv mitgestalten zu k\u00f6nnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gesundheit ist oberste Priorit\u00e4t<\/h3>\n\n\n\n<p>Seit der Corona-Krise ist f\u00fcr die meisten Menschen Gesundheit und Sicherheit oberste Priorit\u00e4t, auch am Arbeitsplatz. Deshalb haben wir bereits vor einigen Wochen ein umfassendes Schutzkonzept erarbeitet und umgesetzt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<p>\u00abEs war uns wichtig, ein Schutzkonzept zu erstellen, das greift und es stetig den neusten Bedingungen anzupassen\u00bb, sagt Andreas Brandl, Mitgr\u00fcnder von FlexOffice. \u00abDas positive Feedback unserer Community zeigt, dass wir richtig gehandelt haben und dass unsere Spaces zu jeder Zeit sicher und unbek\u00fcmmert genutzt werden k\u00f6nnen.\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Das Home-Office-Dilemma<\/h3>\n\n\n\n<p>Viele Firmen hatten jedoch w\u00e4hrend der Corona-Krise ihre Operationen ins Home-Office verlegt und waren \u00fcberrascht, wie gut es sich von zu Hause arbeiten liess. Es ist deshalb anzunehmen, dass das Home-Office in den kommenden Jahren weiterhin eine wichtige Rolle spielen wird.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Flexibilit\u00e4t ist genau das, was Firmen heute brauchen und wollen.<\/p>\n<\/blockquote>\n\n\n\n<p>Gleichzeitig sind durch das Home-Office neue Herausforderungen zum Vorschein gekommen: Nicht alle k\u00f6nnen sich zu Hause gleich gut konzentrieren, sei es wegen L\u00e4rm, Verpflichtungen oder Ablenkung. Zudem vermissen die meisten Menschen den physischen Kontakt zu ihren Kollegen, sei es, um Team-Aufgaben zu bew\u00e4ltigen oder f\u00fcr den informellen Austausch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Flexibilit\u00e4t ist der Schl\u00fcssel<\/h3>\n\n\n\n<p>In Zukunft werden Firmen deshalb noch agiler arbeiten wollen, mit einem Mix aus B\u00fcro, Home-Office und dem beliebten Split-Office.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Wir sind \u00fcberzeugt, dass wir die passenden Arbeitsl\u00f6sungen f\u00fcr die Post-Corona-Zeit bieten.<\/p>\n<\/blockquote>\n\n\n\n<p>Wenn auch immer Mitarbeiter physisch im B\u00fcro zusammenkommen, muss das Arbeitsumfeld den vielf\u00e4ltigen Bed\u00fcrfnissen von Teams entsprechen, so dass effektiv gebrainstormt, geplant und gearbeitet werden kann. Zudem m\u00fcssen anregende und gem\u00fctliche Ecken f\u00fcr den informellen Austausch vorhanden sein.<\/p>\n\n\n\n<p>\u00abMit unseren flexiblen Mietkonditionen, den funktionalen R\u00e4umen und einmaligen Services bietet FlexOffice maximale Flexibilit\u00e4t f\u00fcr Firmen \u2013 und Flexibilit\u00e4t ist genau das, was Firmen heute brauchen und wollen\u00bb, erl\u00e4utert Brandl. \u00abWir sind \u00fcberzeugt, dass wir die passenden Arbeitsl\u00f6sungen f\u00fcr die Post-Corona-Zeit bieten und werden sicherstellen, diese kontinuierlich den neuen Begebenheiten anzupassen.\u00bb<\/p>\n\n\n\n<p><a href=\"https:\/\/flexoffice.swiss\/wp-admin\/post.php?post=91051&amp;action=edit\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie die ganze Schweiz, freute sich auch FlexOffice enorm \u00fcber die Lockerung des Lockdowns. Um so mehr, da alle FlexOffice Standorte wie gewohnt f\u00fcr Mieter, G\u00e4ste und potentielle Kunden ge\u00f6ffnet sind. <\/p>\n","protected":false},"author":22,"featured_media":1677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35,37],"tags":[],"class_list":["post-1676","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-workplace","category-flexoffice-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/posts\/1676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/comments?post=1676"}],"version-history":[{"count":2,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/posts\/1676\/revisions"}],"predecessor-version":[{"id":12063,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/posts\/1676\/revisions\/12063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/media\/1677"}],"wp:attachment":[{"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/media?parent=1676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/categories?post=1676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flexoffice.swiss\/en\/wp-json\/wp\/v2\/tags?post=1676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}