{"id":1678,"date":"2020-06-18T15:09:21","date_gmt":"2020-06-18T15:09:21","guid":{"rendered":"https:\/\/flexoffice.swiss\/die-neue-xoxo-cafe-bar-ist-eroeffnet\/"},"modified":"2025-07-31T11:17:20","modified_gmt":"2025-07-31T11:17:20","slug":"die-neue-xoxo-cafe-bar-ist-eroeffnet","status":"publish","type":"post","link":"https:\/\/flexoffice.swiss\/fr\/die-neue-xoxo-cafe-bar-ist-eroeffnet\/","title":{"rendered":"Die XOXO Caf\u00e9-Bar ist er\u00f6ffnet"},"content":{"rendered":"\n<p>Dieser Erfolg w\u00e4re nicht m\u00f6glich gewesen ohne unsere starke Partnerschaft mit der SV Group, welche die Caf\u00e9-Bar betreibt. Das junge und dynamische Team wird von der 33-j\u00e4hrigen Sabrina Wermann und dem 33-j\u00e4hrigen Simon Janson angef\u00fchrt. Beide bringen viele Jahre Erfahrung aus der Gastro-Branche mit. Auch wenn gerade sehr besch\u00e4ftigt, hat sich Simon bereit erkl\u00e4rt, uns kurz etwas \u00fcber das XOXO zu erz\u00e4hlen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Hi Simon, stell dich doch kurz vor.<\/h4>\n\n\n\n<p>Hallo zusammen, ich bin Simon: verheiratet und der gl\u00fcckliche Vater eines kleinen, s\u00fcssen Babys. Mit der SV Group arbeite ich seit etwas \u00fcber 10 Jahren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wenn du ein Getr\u00e4nk w\u00e4rst, was w\u00e4rst Du?<\/h3>\n\n\n\n<p>Ganz klarer Fall: ein Moscow Mule \u2013 freundlich, erfrischend, mit etwas Sch\u00e4rfe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Was ist die XOXO Caf\u00e9-Bar?<\/h3>\n\n\n\n<p>Die XOXO Caf\u00e9-Bar ist der neue Inn-Place in Basel, im Herzen der Stadt, direkt am Barf\u00fcsserplatz. Wir setzen den Fokus auf regionale Produkte und ein innovatives, erfrischendes Angebot. Auch unser Innendesign ist einzigartig: im Stil \u201eindustrial-chic\u201c, mit wundersch\u00f6ner Kupfer-Bar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Inwiefern unterscheidet sich das XOXO von anderen Caf\u00e9s und Bars in Basel?<\/h3>\n\n\n\n<p>Wir sind Teil des neuen FlexOffice am Barf\u00fcsserplatz \u2013 ein neuartiges Workplace-Konzept, wo Firmen auf 3000m2 Fl\u00e4che modernste B\u00fcros und kollaborative Spaces mieten k\u00f6nnen. Eine Kombi wie diese \u2013 innovatives Arbeiten gekoppelt mit hochklassigem Gastro \u2013 das gab es in Basel noch nie. &nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wer genau ist das Zielpublikum?<\/h3>\n\n\n\n<p>Alle sind hier willkommen. Das Besondere am XOXO ist: wir fungieren als Schnittstelle zwischen dem FlexOffice und der \u00d6ffentlichkeit. Das heisst, wir erwarten ein sehr diverses Publikum und viele spannende und bereichernde Begegnungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Kannst du uns etwas mehr \u00fcber das Angebot erz\u00e4hlen?<\/h3>\n\n\n\n<p>F\u00fcr uns war es wichtig, unseren Kunden neben globalen K\u00f6stlichkeiten auch das Beste aus der Region bieten zu k\u00f6nnen \u2013 egal ob wir von Kaffee sprechen, Bio-Gipfeli oder Quinoa-Bowl. Deshalb haben wir lange nach den richtigen Partnern gesucht, und schlussendlich auch gefunden. Unser Kaffee kommt zum Beispiel von&nbsp;<a href=\"https:\/\/kaffeemacher.ch\/\" target=\"_blank\" rel=\"noopener\">Kaffeemacher<\/a>, einer R\u00f6sterei in M\u00fcnchenstein. Unser Bier kommt von&nbsp;<a href=\"https:\/\/www.kitchenbrew.ch\/\" target=\"_blank\" rel=\"noopener\">Kitchen Brew<\/a>&nbsp;aus Allschwil und der Wein von&nbsp;<a href=\"https:\/\/www.weingutjauslin.ch\/\" target=\"_blank\" rel=\"noopener\">Jauslin<\/a>&nbsp;aus Muttenz. &nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hast du hier bereits etwas Lustiges erlebt?<\/h3>\n\n\n\n<p>An meinem ersten Arbeitstag hat jemand ans Take-Away Fenster geklopft und mich gefragt, ob es hier auch Pianos g\u00e4be. Da war ich ziemlich verwirrt. Ich konnte aber schnell dr\u00fcber lachen und habe die Person auf einen Kaffee eingeladen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Was ist f\u00fcr die Zukunft geplant?<\/h3>\n\n\n\n<p>Jetzt werden wir erst mal mit der Er\u00f6ffnungsphase durchstarten. Dann werden wir uns vor allem darauf konzentrieren, unser Angebot auszubauen. Und \u2013 auch wenn das bis jetzt nicht m\u00f6glich war \u2013 hoffen wir doch, dass wir unsere Er\u00f6ffnungsparty irgendwann nachholen k\u00f6nnen. Wir behalten euch nat\u00fcrlich auf dem Laufenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Deine letzten Worte?<\/h3>\n\n\n\n<p>Kommt herein, schaut euch dieses Bijoux an. Und geniesst unser tolles Angebot!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist soweit! Mit grosser Freude verk\u00fcnden wir, dass die erste XOXO Caf\u00e9-Bar seine T\u00fcren ge\u00f6ffnet hat. Das Lokal am Barf\u00fcsserplatz in Basel ist das erste grosse Gastro-Projekt, das sich FlexOffice auf die Fahne geschrieben hat \u2013 mehr werden folgen.<\/p>\n","protected":false},"author":7,"featured_media":1930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35,37],"tags":[],"class_list":["post-1678","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-workplace","category-flexoffice-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/posts\/1678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/comments?post=1678"}],"version-history":[{"count":7,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/posts\/1678\/revisions"}],"predecessor-version":[{"id":12060,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/posts\/1678\/revisions\/12060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/media\/1930"}],"wp:attachment":[{"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/media?parent=1678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/categories?post=1678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flexoffice.swiss\/fr\/wp-json\/wp\/v2\/tags?post=1678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}